{"id":864,"count":1,"description":"","link":"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/","name":"brush tutorial","slug":"brush-tutorial","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"p:domain_verify\" content=\"9de21be98ff93742a54498309992bf60\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/creationcassel.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/tag\\\/brush-tutorial\\\/#listItem\",\"name\":\"brush tutorial\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/tag\\\/brush-tutorial\\\/#listItem\",\"position\":2,\"name\":\"brush tutorial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/#collectionpage\",\"url\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/\",\"name\":\"brush tutorial | Creation Cassel\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/#organization\",\"name\":\"Creation Cassel\",\"description\":\"Making Memories with PaintShop Pro\",\"url\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/CreationCassel-logo-247.png\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/#organizationLogo\",\"width\":247,\"height\":107},\"image\":{\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/864\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/creation_cassel\\\/\",\"https:\\\/\\\/www.pinterest.ca\\\/creationcassel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYCkEFcwkyuLFdNJiv1wf1A\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/\",\"name\":\"Creation Cassel\",\"description\":\"Making Memories with PaintShop Pro\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/creationcassel.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"brush tutorial | Creation Cassel","description":"","canonical_url":"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"p:domain_verify":"9de21be98ff93742a54498309992bf60","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/creationcassel.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/creationcassel.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/#listItem","name":"brush tutorial"}},{"@type":"ListItem","@id":"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/#listItem","position":2,"name":"brush tutorial","previousItem":{"@type":"ListItem","@id":"https:\/\/creationcassel.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/#collectionpage","url":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/","name":"brush tutorial | Creation Cassel","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/creationcassel.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/creationcassel.com\/blog\/#organization","name":"Creation Cassel","description":"Making Memories with PaintShop Pro","url":"https:\/\/creationcassel.com\/blog\/","logo":{"@type":"ImageObject","url":"https:\/\/creationcassel.com\/blog\/wp-content\/uploads\/2018\/12\/CreationCassel-logo-247.png","@id":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/#organizationLogo","width":247,"height":107},"image":{"@id":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/creation_cassel\/","https:\/\/www.pinterest.ca\/creationcassel\/","https:\/\/www.youtube.com\/channel\/UCYCkEFcwkyuLFdNJiv1wf1A"]},{"@type":"WebSite","@id":"https:\/\/creationcassel.com\/blog\/#website","url":"https:\/\/creationcassel.com\/blog\/","name":"Creation Cassel","description":"Making Memories with PaintShop Pro","inLanguage":"en-US","publisher":{"@id":"https:\/\/creationcassel.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/creationcassel.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tbrush tutorial\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/creationcassel.com\/blog"},{"label":"brush tutorial","link":"https:\/\/creationcassel.com\/blog\/tag\/brush-tutorial\/"}],"_links":{"self":[{"href":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags\/864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/creationcassel.com\/blog\/wp-json\/wp\/v2\/posts?tags=864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}